{"id":68,"count":4,"description":"","link":"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores","name":"Computers","slug":"ordenadores","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordenadores archivos | Mola Mola Dive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordenadores archivos | Mola Mola Dive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores\" \/>\n<meta property=\"og:site_name\" content=\"Mola Mola Dive\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/tienda-buceo\\\/ordenadores\",\"url\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/tienda-buceo\\\/ordenadores\",\"name\":\"Ordenadores archivos | Mola Mola Dive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/tienda-buceo\\\/ordenadores#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/tienda-buceo\\\/ordenadores#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/molamoladive.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordenadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/\",\"name\":\"Mola Mola Dive\",\"description\":\"Centro de buceo especializado en viajes por el mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/#organization\",\"name\":\"Mola Mola Dive\",\"url\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/molamoladive.es\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo-Mola-Mola-Sin-Fondo-PNG.png\",\"contentUrl\":\"https:\\\/\\\/molamoladive.es\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo-Mola-Mola-Sin-Fondo-PNG.png\",\"width\":188,\"height\":200,\"caption\":\"Mola Mola Dive\"},\"image\":{\"@id\":\"https:\\\/\\\/molamoladive.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordenadores archivos | Mola Mola Dive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores","og_locale":"en_GB","og_type":"article","og_title":"Ordenadores archivos | Mola Mola Dive","og_url":"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores","og_site_name":"Mola Mola Dive","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores","url":"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores","name":"Ordenadores archivos | Mola Mola Dive","isPartOf":{"@id":"https:\/\/molamoladive.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/molamoladive.es\/en\/tienda-buceo\/ordenadores#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/molamoladive.es\/"},{"@type":"ListItem","position":2,"name":"Ordenadores"}]},{"@type":"WebSite","@id":"https:\/\/molamoladive.es\/en\/#website","url":"https:\/\/molamoladive.es\/en\/","name":"Mola Mola Dive","description":"Diving center specializing in trips around the world","publisher":{"@id":"https:\/\/molamoladive.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/molamoladive.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/molamoladive.es\/en\/#organization","name":"Mola Mola Dive","url":"https:\/\/molamoladive.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/molamoladive.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/molamoladive.es\/wp-content\/uploads\/2022\/01\/Logo-Mola-Mola-Sin-Fondo-PNG.png","contentUrl":"https:\/\/molamoladive.es\/wp-content\/uploads\/2022\/01\/Logo-Mola-Mola-Sin-Fondo-PNG.png","width":188,"height":200,"caption":"Mola Mola Dive"},"image":{"@id":"https:\/\/molamoladive.es\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/molamoladive.es\/en\/wp-json\/wp\/v2\/product_cat\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/molamoladive.es\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/molamoladive.es\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/molamoladive.es\/en\/wp-json\/wp\/v2\/product?product_cat=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}